{"id":12275,"date":"2015-01-14T09:43:41","date_gmt":"2015-01-14T09:43:41","guid":{"rendered":"http:\/\/www.enusa.es\/?p=625"},"modified":"2024-02-07T16:19:27","modified_gmt":"2024-02-07T15:19:27","slug":"la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3","status":"publish","type":"post","link":"https:\/\/www.enusa.es\/en\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/","title":{"rendered":"La f\u00e1brica de Juzbado comunica un suceso notificable al Consejo de Seguridad Nuclear."},"content":{"rendered":"<p>A las 10:30 horas de esta ma\u00f1ana se ha producido una falsa alarma en el Sistema de Alarma de Criticidad de la f\u00e1brica de combustible de Juzbado. La activaci\u00f3n de la alarma se ha debido a un error humano cometido cuando se realizaban tareas de mantenimiento derivadas de la resoluci\u00f3n del problema que origin\u00f3 la falsa alarma del pasado 3 de enero.<\/p>\n<p>Se ha evacuado al personal siguiendo los procedimientos establecidos.<\/p>\n<p>El incidente no ha supuesto ning\u00fan riesgo para la instalaci\u00f3n, ni para los trabajadores, ni para el p\u00fablico, ni para el medio ambiente.<\/p>","protected":false},"excerpt":{"rendered":"<p>A las 10:30 horas de esta ma\u00f1ana se ha producido una falsa alarma en el Sistema de Alarma de Criticidad de la f\u00e1brica de combustible de Juzbado. La activaci\u00f3n de la alarma se ha debido a un error humano cometido cuando se realizaban tareas de mantenimiento derivadas de la resoluci\u00f3n del problema que origin\u00f3 la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-12275","post","type-post","status-publish","format-standard","hentry","category-notas-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La f\u00e1brica de Juzbado comunica un suceso notificable al Consejo de Seguridad Nuclear. - ENUSA | A company for the future<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.enusa.es\/en\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La f\u00e1brica de Juzbado comunica un suceso notificable al Consejo de Seguridad Nuclear. - ENUSA | A company for the future\" \/>\n<meta property=\"og:description\" content=\"A las 10:30 horas de esta ma\u00f1ana se ha producido una falsa alarma en el Sistema de Alarma de Criticidad de la f\u00e1brica de combustible de Juzbado. La activaci\u00f3n de la alarma se ha debido a un error humano cometido cuando se realizaban tareas de mantenimiento derivadas de la resoluci\u00f3n del problema que origin\u00f3 la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.enusa.es\/en\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/\" \/>\n<meta property=\"og:site_name\" content=\"ENUSA | A company for the future\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-14T09:43:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T15:19:27+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/73d26d37c3085056c46d2e7d987fe9ce\"},\"headline\":\"La f\u00e1brica de Juzbado comunica un suceso notificable al Consejo de Seguridad Nuclear.\",\"datePublished\":\"2015-01-14T09:43:41+00:00\",\"dateModified\":\"2024-02-07T15:19:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\\\/\"},\"wordCount\":113,\"articleSection\":[\"Notas de prensa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\\\/\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\\\/\",\"name\":\"La f\u00e1brica de Juzbado comunica un suceso notificable al Consejo de Seguridad Nuclear. - ENUSA | A company for the future\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\"},\"datePublished\":\"2015-01-14T09:43:41+00:00\",\"dateModified\":\"2024-02-07T15:19:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/73d26d37c3085056c46d2e7d987fe9ce\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.enusa.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La f\u00e1brica de Juzbado comunica un suceso notificable al Consejo de Seguridad Nuclear.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/\",\"name\":\"ENUSA | A company for the future\",\"description\":\"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.enusa.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/73d26d37c3085056c46d2e7d987fe9ce\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.enusa.es\"],\"url\":\"https:\\\/\\\/www.enusa.es\\\/en\\\/author\\\/divi-d55labs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La f\u00e1brica de Juzbado comunica un suceso notificable al Consejo de Seguridad Nuclear. - ENUSA | A company for the future","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.enusa.es\/en\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/","og_locale":"en_GB","og_type":"article","og_title":"La f\u00e1brica de Juzbado comunica un suceso notificable al Consejo de Seguridad Nuclear. - ENUSA | A company for the future","og_description":"A las 10:30 horas de esta ma\u00f1ana se ha producido una falsa alarma en el Sistema de Alarma de Criticidad de la f\u00e1brica de combustible de Juzbado. La activaci\u00f3n de la alarma se ha debido a un error humano cometido cuando se realizaban tareas de mantenimiento derivadas de la resoluci\u00f3n del problema que origin\u00f3 la [&hellip;]","og_url":"https:\/\/www.enusa.es\/en\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/","og_site_name":"ENUSA | A company for the future","article_published_time":"2015-01-14T09:43:41+00:00","article_modified_time":"2024-02-07T15:19:27+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/#article","isPartOf":{"@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/"},"author":{"name":"admin","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/73d26d37c3085056c46d2e7d987fe9ce"},"headline":"La f\u00e1brica de Juzbado comunica un suceso notificable al Consejo de Seguridad Nuclear.","datePublished":"2015-01-14T09:43:41+00:00","dateModified":"2024-02-07T15:19:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/"},"wordCount":113,"articleSection":["Notas de prensa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/","url":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/","name":"La f\u00e1brica de Juzbado comunica un suceso notificable al Consejo de Seguridad Nuclear. - ENUSA | A company for the future","isPartOf":{"@id":"https:\/\/www.enusa.es\/#website"},"datePublished":"2015-01-14T09:43:41+00:00","dateModified":"2024-02-07T15:19:27+00:00","author":{"@id":"https:\/\/www.enusa.es\/#\/schema\/person\/73d26d37c3085056c46d2e7d987fe9ce"},"breadcrumb":{"@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.enusa.es\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-comunica-un-suceso-notificable-al-consejo-de-seguridad-nuclear-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.enusa.es\/"},{"@type":"ListItem","position":2,"name":"La f\u00e1brica de Juzbado comunica un suceso notificable al Consejo de Seguridad Nuclear."}]},{"@type":"WebSite","@id":"https:\/\/www.enusa.es\/#website","url":"https:\/\/www.enusa.es\/","name":"ENUSA | A company for the future","description":"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.enusa.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/73d26d37c3085056c46d2e7d987fe9ce","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.enusa.es"],"url":"https:\/\/www.enusa.es\/en\/author\/divi-d55labs\/"}]}},"_links":{"self":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/12275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/comments?post=12275"}],"version-history":[{"count":1,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/12275\/revisions"}],"predecessor-version":[{"id":20010,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/12275\/revisions\/20010"}],"wp:attachment":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/media?parent=12275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/categories?post=12275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/tags?post=12275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}