{"id":1667,"date":"2015-05-12T17:45:23","date_gmt":"2015-05-12T17:45:23","guid":{"rendered":"http:\/\/www.enusa.es\/?p=1667"},"modified":"2024-02-07T16:16:22","modified_gmt":"2024-02-07T15:16:22","slug":"emgrisa-presenta-su-oficina-en-peru","status":"publish","type":"post","link":"https:\/\/www.enusa.es\/en\/emgrisa-presenta-su-oficina-en-peru\/","title":{"rendered":"EMGRISA presenta su oficina en Per\u00fa"},"content":{"rendered":"<p><a href=\"http:\/\/www.emgrisa.es\" target=\"_blank\" rel=\"noopener noreferrer\">EMGRISA,<\/a> empresa del GRUPO ENUSA que desarrolla servicios medioambientales, present\u00f3 ayer su delegaci\u00f3n de Per\u00fa a diversas compa\u00f1\u00edas y representantes de la Administraci\u00f3n en Lima.<\/p>\n<p>El Presidente de EMGRISA, D. Jos\u00e9 Luis Gonz\u00e1lez Mart\u00ednez, el Director General, D. Mariano Mart\u00ednez Cepa, el Director T\u00e9cnico, D. Alfonso \u00c1lvarez Rodr\u00edguez, y el Delegado de EMGRISA en Per\u00fa, D. Jos\u00e9 \u00c1ngel Andr\u00e9s Anad\u00f3n, han sido los encargados de realizar la presentaci\u00f3n de la organizaci\u00f3n introduciendo los servicios ambientales y proyectos en los que EMGRISA ha participado.<\/p>\n<p>Per\u00fa est\u00e1 experimentando un crecimiento importante en las primeras fases de los servicios que ofrece EMGRISA, investigaci\u00f3n e identificaci\u00f3n de contaminaci\u00f3n. Adem\u00e1s, dispone de un desarrollo normativo medioambiental muy exigente, aunque poca experiencia en los servicios en los que EMGRISA es un referente en nuestro pa\u00eds, con gran experiencia y capacidad para abordar remediaciones de envergadura.<\/p>\n<p>Con una avalada experiencia, EMGRISA, desde su sucursal en Per\u00fa busca prestar servicios de descontaminaci\u00f3n de suelos y aguas subterr\u00e1neas, gesti\u00f3n de una amplia gama de residuos (agroalimentarios, s\u00f3lidos urbanos, industriales, etc.), restauraci\u00f3n minera, consultor\u00eda e ingenier\u00eda ambiental y asistencia t\u00e9cnica al sector privado y administraciones p\u00fablicas, tanto en el propio Per\u00fa como en el resto de pa\u00edses latinoamericanos.<\/p>\n<p><a href=\"http:\/\/www.efe.com\/efe\/noticias\/espana\/economia\/empresa-espanola-gestion-residuos-emgrisa-presento-peru\/1\/8\/2609899\" target=\"_blank\" rel=\"noopener noreferrer\">Ver informaci\u00f3n y video de la AGENCIA EFE<\/a><\/p>\n<h3><strong>EMGRISA estrena nueva imagen<\/strong><\/h3>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.enusa.es\/wp-content\/uploads\/2015\/05\/logo-emgrisa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-1669\" title=\"Nuevo logo EMGRISA\" src=\"http:\/\/www.enusa.es\/wp-content\/uploads\/2015\/05\/logo-emgrisa-300x106.jpg\" alt=\"Nuevo logo EMGRISA\" width=\"314\" height=\"111\" \/><\/a>Coincidiendo con el 25\u00ba Aniversario y con su expansi\u00f3n internacional, EMGRISA presenta una nueva identidad visual conservando su imagotipo redondo de su anterior logo y respetando los colores corporativos del logo del GRUPO ENUSA. Imagen renovada y acorde a los nuevos tiempos y a los nuevos proyectos a los que se enfrenta.<\/p>\n<h3><strong>Premio \u201cEl Suplemento 2015\u201d<\/strong><\/h3>\n<p>EMGRISA recibi\u00f3 el pasado viernes el Premio \u201cEl Suplemento 2015\u201d en categor\u00eda de gesti\u00f3n medioambiental. Premio que reconoce la labor y actividad de nuestra empresa filial en el sector medioambiental y, en concreto, el disponer de medios y tecnolog\u00eda propios que permiten desarrollar una amplia tipolog\u00eda de estudios, proyectos y obras relacionadas con suelos contaminados y aguas subterr\u00e1neas, consultor\u00eda y gesti\u00f3n ambiental, as\u00ed como la gesti\u00f3n de distintos tipos de residuos industriales.<\/p>\n<p><a href=\"https:\/\/youtu.be\/BVbSgMgc4pA\" target=\"_blank\" rel=\"noopener noreferrer\">Gala Premios El Suplemento 2015<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>EMGRISA, empresa del GRUPO ENUSA que desarrolla servicios medioambientales, present\u00f3 ayer su delegaci\u00f3n de Per\u00fa a diversas compa\u00f1\u00edas y representantes de la Administraci\u00f3n en Lima. El Presidente de EMGRISA, D. Jos\u00e9 Luis Gonz\u00e1lez Mart\u00ednez, el Director General, D. Mariano Mart\u00ednez Cepa, el Director T\u00e9cnico, D. Alfonso \u00c1lvarez Rodr\u00edguez, y el Delegado de EMGRISA en Per\u00fa, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-1667","post","type-post","status-publish","format-standard","hentry","category-notas-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EMGRISA presenta su oficina en Per\u00fa - ENUSA | A company for the future<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.enusa.es\/en\/emgrisa-presenta-su-oficina-en-peru\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMGRISA presenta su oficina en Per\u00fa - ENUSA | A company for the future\" \/>\n<meta property=\"og:description\" content=\"EMGRISA, empresa del GRUPO ENUSA que desarrolla servicios medioambientales, present\u00f3 ayer su delegaci\u00f3n de Per\u00fa a diversas compa\u00f1\u00edas y representantes de la Administraci\u00f3n en Lima. El Presidente de EMGRISA, D. Jos\u00e9 Luis Gonz\u00e1lez Mart\u00ednez, el Director General, D. Mariano Mart\u00ednez Cepa, el Director T\u00e9cnico, D. Alfonso \u00c1lvarez Rodr\u00edguez, y el Delegado de EMGRISA en Per\u00fa, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.enusa.es\/en\/emgrisa-presenta-su-oficina-en-peru\/\" \/>\n<meta property=\"og:site_name\" content=\"ENUSA | A company for the future\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-12T17:45:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T15:16:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.enusa.es\/wp-content\/uploads\/2015\/05\/logo-emgrisa-300x106.jpg\" \/>\n<meta name=\"author\" content=\"Ignacio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ignacio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/\"},\"author\":{\"name\":\"Ignacio\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"headline\":\"EMGRISA presenta su oficina en Per\u00fa\",\"datePublished\":\"2015-05-12T17:45:23+00:00\",\"dateModified\":\"2024-02-07T15:16:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/\"},\"wordCount\":382,\"image\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/logo-emgrisa-300x106.jpg\",\"articleSection\":[\"Notas de prensa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/\",\"name\":\"EMGRISA presenta su oficina en Per\u00fa - ENUSA | A company for the future\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/logo-emgrisa-300x106.jpg\",\"datePublished\":\"2015-05-12T17:45:23+00:00\",\"dateModified\":\"2024-02-07T15:16:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/logo-emgrisa-300x106.jpg\",\"contentUrl\":\"http:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/logo-emgrisa-300x106.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/emgrisa-presenta-su-oficina-en-peru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.enusa.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EMGRISA presenta su oficina en Per\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/\",\"name\":\"ENUSA | A company for the future\",\"description\":\"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.enusa.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\",\"name\":\"Ignacio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"caption\":\"Ignacio\"},\"url\":\"https:\\\/\\\/www.enusa.es\\\/en\\\/author\\\/admin-enusa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EMGRISA presenta su oficina en Per\u00fa - ENUSA | A company for the future","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.enusa.es\/en\/emgrisa-presenta-su-oficina-en-peru\/","og_locale":"en_GB","og_type":"article","og_title":"EMGRISA presenta su oficina en Per\u00fa - ENUSA | A company for the future","og_description":"EMGRISA, empresa del GRUPO ENUSA que desarrolla servicios medioambientales, present\u00f3 ayer su delegaci\u00f3n de Per\u00fa a diversas compa\u00f1\u00edas y representantes de la Administraci\u00f3n en Lima. El Presidente de EMGRISA, D. Jos\u00e9 Luis Gonz\u00e1lez Mart\u00ednez, el Director General, D. Mariano Mart\u00ednez Cepa, el Director T\u00e9cnico, D. Alfonso \u00c1lvarez Rodr\u00edguez, y el Delegado de EMGRISA en Per\u00fa, [&hellip;]","og_url":"https:\/\/www.enusa.es\/en\/emgrisa-presenta-su-oficina-en-peru\/","og_site_name":"ENUSA | A company for the future","article_published_time":"2015-05-12T17:45:23+00:00","article_modified_time":"2024-02-07T15:16:22+00:00","og_image":[{"url":"http:\/\/www.enusa.es\/wp-content\/uploads\/2015\/05\/logo-emgrisa-300x106.jpg","type":"","width":"","height":""}],"author":"Ignacio","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ignacio","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/#article","isPartOf":{"@id":"https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/"},"author":{"name":"Ignacio","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"headline":"EMGRISA presenta su oficina en Per\u00fa","datePublished":"2015-05-12T17:45:23+00:00","dateModified":"2024-02-07T15:16:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/"},"wordCount":382,"image":{"@id":"https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/#primaryimage"},"thumbnailUrl":"http:\/\/www.enusa.es\/wp-content\/uploads\/2015\/05\/logo-emgrisa-300x106.jpg","articleSection":["Notas de prensa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/","url":"https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/","name":"EMGRISA presenta su oficina en Per\u00fa - ENUSA | A company for the future","isPartOf":{"@id":"https:\/\/www.enusa.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/#primaryimage"},"image":{"@id":"https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/#primaryimage"},"thumbnailUrl":"http:\/\/www.enusa.es\/wp-content\/uploads\/2015\/05\/logo-emgrisa-300x106.jpg","datePublished":"2015-05-12T17:45:23+00:00","dateModified":"2024-02-07T15:16:22+00:00","author":{"@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"breadcrumb":{"@id":"https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/#primaryimage","url":"http:\/\/www.enusa.es\/wp-content\/uploads\/2015\/05\/logo-emgrisa-300x106.jpg","contentUrl":"http:\/\/www.enusa.es\/wp-content\/uploads\/2015\/05\/logo-emgrisa-300x106.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.enusa.es\/emgrisa-presenta-su-oficina-en-peru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.enusa.es\/"},{"@type":"ListItem","position":2,"name":"EMGRISA presenta su oficina en Per\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/www.enusa.es\/#website","url":"https:\/\/www.enusa.es\/","name":"ENUSA | A company for the future","description":"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.enusa.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834","name":"Ignacio","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","caption":"Ignacio"},"url":"https:\/\/www.enusa.es\/en\/author\/admin-enusa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/1667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/comments?post=1667"}],"version-history":[{"count":2,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/1667\/revisions"}],"predecessor-version":[{"id":20007,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/1667\/revisions\/20007"}],"wp:attachment":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/media?parent=1667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/categories?post=1667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/tags?post=1667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}