{"id":18510,"date":"2015-02-01T09:44:07","date_gmt":"2015-02-01T09:44:07","guid":{"rendered":"http:\/\/www.enusa.es\/?p=190"},"modified":"2024-01-19T08:47:24","modified_gmt":"2024-01-19T07:47:24","slug":"servicios-medioambientales","status":"publish","type":"post","link":"https:\/\/www.enusa.es\/en\/servicios-medioambientales\/","title":{"rendered":"Servicios medioambientales"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-18510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servicios medioambientales - ENUSA | A company for the future<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.enusa.es\/en\/servicios-medioambientales\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicios medioambientales - ENUSA | A company for the future\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.enusa.es\/en\/servicios-medioambientales\/\" \/>\n<meta property=\"og:site_name\" content=\"ENUSA | A company for the future\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-01T09:44:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-19T07:47:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.enusa.es\/wp-content\/uploads\/2015\/02\/serviciosmedioambientales-943x345-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"943\" \/>\n\t<meta property=\"og:image:height\" content=\"345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ignacio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ignacio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/\"},\"author\":{\"name\":\"Ignacio\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"headline\":\"Servicios medioambientales\",\"datePublished\":\"2015-02-01T09:44:07+00:00\",\"dateModified\":\"2024-01-19T07:47:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/\"},\"wordCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/serviciosmedioambientales-943x345-1.jpg\",\"articleSection\":[\"Notas de prensa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/\",\"name\":\"Servicios medioambientales - ENUSA | A company for the future\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/serviciosmedioambientales-943x345-1.jpg\",\"datePublished\":\"2015-02-01T09:44:07+00:00\",\"dateModified\":\"2024-01-19T07:47:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/serviciosmedioambientales-943x345-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/serviciosmedioambientales-943x345-1.jpg\",\"width\":943,\"height\":345},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/servicios-medioambientales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.enusa.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios medioambientales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/\",\"name\":\"ENUSA | A company for the future\",\"description\":\"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.enusa.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\",\"name\":\"Ignacio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"caption\":\"Ignacio\"},\"url\":\"https:\\\/\\\/www.enusa.es\\\/en\\\/author\\\/admin-enusa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servicios medioambientales - ENUSA | A company for the future","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.enusa.es\/en\/servicios-medioambientales\/","og_locale":"en_GB","og_type":"article","og_title":"Servicios medioambientales - ENUSA | A company for the future","og_url":"https:\/\/www.enusa.es\/en\/servicios-medioambientales\/","og_site_name":"ENUSA | A company for the future","article_published_time":"2015-02-01T09:44:07+00:00","article_modified_time":"2024-01-19T07:47:24+00:00","og_image":[{"width":943,"height":345,"url":"https:\/\/www.enusa.es\/wp-content\/uploads\/2015\/02\/serviciosmedioambientales-943x345-1.jpg","type":"image\/jpeg"}],"author":"Ignacio","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ignacio"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.enusa.es\/servicios-medioambientales\/#article","isPartOf":{"@id":"https:\/\/www.enusa.es\/servicios-medioambientales\/"},"author":{"name":"Ignacio","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"headline":"Servicios medioambientales","datePublished":"2015-02-01T09:44:07+00:00","dateModified":"2024-01-19T07:47:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.enusa.es\/servicios-medioambientales\/"},"wordCount":2,"image":{"@id":"https:\/\/www.enusa.es\/servicios-medioambientales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.enusa.es\/wp-content\/uploads\/2015\/02\/serviciosmedioambientales-943x345-1.jpg","articleSection":["Notas de prensa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.enusa.es\/servicios-medioambientales\/","url":"https:\/\/www.enusa.es\/servicios-medioambientales\/","name":"Servicios medioambientales - ENUSA | A company for the future","isPartOf":{"@id":"https:\/\/www.enusa.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.enusa.es\/servicios-medioambientales\/#primaryimage"},"image":{"@id":"https:\/\/www.enusa.es\/servicios-medioambientales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.enusa.es\/wp-content\/uploads\/2015\/02\/serviciosmedioambientales-943x345-1.jpg","datePublished":"2015-02-01T09:44:07+00:00","dateModified":"2024-01-19T07:47:24+00:00","author":{"@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"breadcrumb":{"@id":"https:\/\/www.enusa.es\/servicios-medioambientales\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.enusa.es\/servicios-medioambientales\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.enusa.es\/servicios-medioambientales\/#primaryimage","url":"https:\/\/www.enusa.es\/wp-content\/uploads\/2015\/02\/serviciosmedioambientales-943x345-1.jpg","contentUrl":"https:\/\/www.enusa.es\/wp-content\/uploads\/2015\/02\/serviciosmedioambientales-943x345-1.jpg","width":943,"height":345},{"@type":"BreadcrumbList","@id":"https:\/\/www.enusa.es\/servicios-medioambientales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.enusa.es\/"},{"@type":"ListItem","position":2,"name":"Servicios medioambientales"}]},{"@type":"WebSite","@id":"https:\/\/www.enusa.es\/#website","url":"https:\/\/www.enusa.es\/","name":"ENUSA | A company for the future","description":"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.enusa.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834","name":"Ignacio","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","caption":"Ignacio"},"url":"https:\/\/www.enusa.es\/en\/author\/admin-enusa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/18510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/comments?post=18510"}],"version-history":[{"count":1,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/18510\/revisions"}],"predecessor-version":[{"id":18599,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/18510\/revisions\/18599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/media\/2070"}],"wp:attachment":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/media?parent=18510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/categories?post=18510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/tags?post=18510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}