{"id":1976,"date":"2015-09-17T14:49:41","date_gmt":"2015-09-17T14:49:41","guid":{"rendered":"http:\/\/www.enusa.es\/?p=1976"},"modified":"2024-02-07T16:08:39","modified_gmt":"2024-02-07T15:08:39","slug":"la-fabrica-de-juzbado-realiza-su-simulacro-anual","status":"publish","type":"post","link":"https:\/\/www.enusa.es\/en\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/","title":{"rendered":"La f\u00e1brica de Juzbado realiza su simulacro anual de emergencia"},"content":{"rendered":"<blockquote>\n<h5>Un accidente de criticidad tras caer tres bidones de polvo, eje del simulacro anual de emergencia de la f\u00e1brica de Juzbado<\/h5>\n<h5>Como consecuencia, cuatro trabajadores sufrieron irradiaci\u00f3n y contaminaci\u00f3n.<\/h5>\n<h5>Una vez m\u00e1s, el simulacro ha puesto de manifiesto el correcto funcionamiento de la organizaci\u00f3n de emergencias de Enusa y de los medios disponibles.<\/h5>\n<\/blockquote>\n<p>Esta ma\u00f1ana, la f\u00e1brica de elementos combustibles de Juzbado ha realizado el simulacro anual de emergencia, que se ha desarrollado entre las 10:30 y las 12:00 horas.<\/p>\n<p>En esta ocasi\u00f3n, el suceso que se ha recreado ha sido un accidente de criticidad que se produce por la acumulaci\u00f3n de material nuclear tras la ca\u00edda y apertura de tres bidones de polvo de \u00f3xido de uranio.<\/p>\n<p>El suceso se inicia en el almac\u00e9n de polvo, cuando un operario que manejaba una carretilla realiza una maniobra brusca y golpea fuertemente dos bidones que se encontraban sobre un camino de rodillos. Ambos bidones caen y se abren derramando polvo de uranio. Un tercer bid\u00f3n queda en posici\u00f3n inestable y finalmente tambi\u00e9n cae en la misma zona, con lo que se produce una situaci\u00f3n que origina un accidente de criticidad.<\/p>\n<p>Como resultado, dos operarios resultan contaminados e irradiados y otros dos m\u00e1s, solamente irradiados.<\/p>\n<p>Se procede a la evacuaci\u00f3n del personal de la instalaci\u00f3n y los cuatro trabajadores afectados son atendidos por el Servicio M\u00e9dico de Enusa. La reacci\u00f3n de criticidad se extingue por s\u00ed sola y en ese momento se da por finalizado el simulacro volviendo la instalaci\u00f3n a la normalidad.<\/p>\n<p>El simulacro forma parte de los requerimientos del Plan de Emergencia Interior de Juzbado. Este tipo de actuaciones se realizan peri\u00f3dicamente en las instalaciones nucleares para comprobar el correcto funcionamiento de la Organizaci\u00f3n de Emergencia, la disposibilidad de los medios y la coordinaci\u00f3n con los organismos implicados.<\/p>\n<p>En este caso, el simulacro se ha desarrollado correctamente y dentro de la normalidad.<\/p>\n<p>Para m\u00e1s informaci\u00f3n, consultar la p\u00e1gina web del <a href=\"https:\/\/www.csn.es\/noticias-csn\/-\/asset_publisher\/tbX5DqDjPdHo\/content\/simulacro-de-emergencia-en-la-fabrica-de-combustible-de-juzbado-salamanc-1\" target=\"_blank\" rel=\"noopener noreferrer\">Consejo de Seguridad Nuclear<\/a> donde queda recogida esta actuaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un accidente de criticidad tras caer tres bidones de polvo, eje del simulacro anual de emergencia de la f\u00e1brica de Juzbado Como consecuencia, cuatro trabajadores sufrieron irradiaci\u00f3n y contaminaci\u00f3n. Una vez m\u00e1s, el simulacro ha puesto de manifiesto el correcto funcionamiento de la organizaci\u00f3n de emergencias de Enusa y de los medios disponibles. Esta ma\u00f1ana, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-1976","post","type-post","status-publish","format-standard","hentry","category-notas-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La f\u00e1brica de Juzbado realiza su simulacro anual de emergencia - ENUSA | A company for the future<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.enusa.es\/en\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La f\u00e1brica de Juzbado realiza su simulacro anual de emergencia - ENUSA | A company for the future\" \/>\n<meta property=\"og:description\" content=\"Un accidente de criticidad tras caer tres bidones de polvo, eje del simulacro anual de emergencia de la f\u00e1brica de Juzbado Como consecuencia, cuatro trabajadores sufrieron irradiaci\u00f3n y contaminaci\u00f3n. Una vez m\u00e1s, el simulacro ha puesto de manifiesto el correcto funcionamiento de la organizaci\u00f3n de emergencias de Enusa y de los medios disponibles. Esta ma\u00f1ana, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.enusa.es\/en\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/\" \/>\n<meta property=\"og:site_name\" content=\"ENUSA | A company for the future\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-17T14:49:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T15:08:39+00:00\" \/>\n<meta name=\"author\" content=\"Ignacio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ignacio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\\\/\"},\"author\":{\"name\":\"Ignacio\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"headline\":\"La f\u00e1brica de Juzbado realiza su simulacro anual de emergencia\",\"datePublished\":\"2015-09-17T14:49:41+00:00\",\"dateModified\":\"2024-02-07T15:08:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\\\/\"},\"wordCount\":366,\"articleSection\":[\"Notas de prensa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\\\/\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\\\/\",\"name\":\"La f\u00e1brica de Juzbado realiza su simulacro anual de emergencia - ENUSA | A company for the future\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\"},\"datePublished\":\"2015-09-17T14:49:41+00:00\",\"dateModified\":\"2024-02-07T15:08:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.enusa.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La f\u00e1brica de Juzbado realiza su simulacro anual de emergencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/\",\"name\":\"ENUSA | A company for the future\",\"description\":\"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.enusa.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\",\"name\":\"Ignacio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"caption\":\"Ignacio\"},\"url\":\"https:\\\/\\\/www.enusa.es\\\/en\\\/author\\\/admin-enusa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La f\u00e1brica de Juzbado realiza su simulacro anual de emergencia - ENUSA | A company for the future","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.enusa.es\/en\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/","og_locale":"en_GB","og_type":"article","og_title":"La f\u00e1brica de Juzbado realiza su simulacro anual de emergencia - ENUSA | A company for the future","og_description":"Un accidente de criticidad tras caer tres bidones de polvo, eje del simulacro anual de emergencia de la f\u00e1brica de Juzbado Como consecuencia, cuatro trabajadores sufrieron irradiaci\u00f3n y contaminaci\u00f3n. Una vez m\u00e1s, el simulacro ha puesto de manifiesto el correcto funcionamiento de la organizaci\u00f3n de emergencias de Enusa y de los medios disponibles. Esta ma\u00f1ana, [&hellip;]","og_url":"https:\/\/www.enusa.es\/en\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/","og_site_name":"ENUSA | A company for the future","article_published_time":"2015-09-17T14:49:41+00:00","article_modified_time":"2024-02-07T15:08:39+00:00","author":"Ignacio","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ignacio","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/#article","isPartOf":{"@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/"},"author":{"name":"Ignacio","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"headline":"La f\u00e1brica de Juzbado realiza su simulacro anual de emergencia","datePublished":"2015-09-17T14:49:41+00:00","dateModified":"2024-02-07T15:08:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/"},"wordCount":366,"articleSection":["Notas de prensa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/","url":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/","name":"La f\u00e1brica de Juzbado realiza su simulacro anual de emergencia - ENUSA | A company for the future","isPartOf":{"@id":"https:\/\/www.enusa.es\/#website"},"datePublished":"2015-09-17T14:49:41+00:00","dateModified":"2024-02-07T15:08:39+00:00","author":{"@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"breadcrumb":{"@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.enusa.es\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.enusa.es\/la-fabrica-de-juzbado-realiza-su-simulacro-anual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.enusa.es\/"},{"@type":"ListItem","position":2,"name":"La f\u00e1brica de Juzbado realiza su simulacro anual de emergencia"}]},{"@type":"WebSite","@id":"https:\/\/www.enusa.es\/#website","url":"https:\/\/www.enusa.es\/","name":"ENUSA | A company for the future","description":"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.enusa.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834","name":"Ignacio","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","caption":"Ignacio"},"url":"https:\/\/www.enusa.es\/en\/author\/admin-enusa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/1976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/comments?post=1976"}],"version-history":[{"count":1,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/1976\/revisions"}],"predecessor-version":[{"id":19998,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/1976\/revisions\/19998"}],"wp:attachment":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/media?parent=1976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/categories?post=1976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/tags?post=1976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}