{"id":2465,"date":"2016-04-06T08:00:14","date_gmt":"2016-04-06T08:00:14","guid":{"rendered":"http:\/\/www.enusa.es\/?p=2465"},"modified":"2024-02-07T16:01:42","modified_gmt":"2024-02-07T15:01:42","slug":"enusa-presente-desde-hoy-en-la-feria-nuclear-china","status":"publish","type":"post","link":"https:\/\/www.enusa.es\/en\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/","title":{"rendered":"ENUSA presente desde hoy en la Feria Nuclear china"},"content":{"rendered":"<p>ENUSA ha viajado a Pek\u00edn, junto a otras empresas nucleares espa\u00f1olas y coordinadas por el <a href=\"http:\/\/www.foronuclear.org\/es\/sala-de-prensa\/notas-de-prensa\/122185-la-industria-nuclear-espanola-compite-en-china-por-un-mercado-en-crecimiento\" target=\"_blank\" rel=\"noopener noreferrer\">Foro de la Industria Nuclear Espa\u00f1ola<\/a>, para participar en la <a href=\"http:\/\/www.nic-expo.net\/\" target=\"_blank\" rel=\"noopener noreferrer\">Nuclear Industry China<\/a> (NIC 2016) que se celebra del 6 al 9 de abril.<\/p>\n<p>La participaci\u00f3n en la Feria NIC es una oportunidad para dar a conocer las novedades de la empresa a lo largo del \u00faltimo a\u00f1o y establecer contactos con las empresas del sector del combustible nuclear chino y de otros pa\u00edses y regiones participantes en la exposici\u00f3n. Asimismo, la presencia del personal de ENUSA en China permite realizar un seguimiento in situ de los proyectos en curso y oportunidades en negociaci\u00f3n con los clientes chinos, por lo que esta Feria constituye el principal acontecimiento de promoci\u00f3n de ENUSA en la regi\u00f3n Asia-Pac\u00edfico.<\/p>\n<p>ENUSA apost\u00f3 por China en 2007, formando parte del <a href=\"http:\/\/www.sngc.es\/en\/\" target=\"_blank\" rel=\"noopener noreferrer\">Spanish Nuclear Group for Cooperation<\/a> y participando en la Exposici\u00f3n Nuclear Internacional celebrada ese a\u00f1o en Shanghai. Tras un primer per\u00edodo de toma de contacto y posicionamiento, ENUSA ha identificado un nicho de negocio en la comercializaci\u00f3n de equipos de inspecci\u00f3n de combustible nuclear, un \u00e1rea en la que las empresas chinas a\u00fan no han logrado el nivel de desarrollo tecnol\u00f3gico alcanzado en Europa o en Estados Unidos, principales proveedores de tecnolog\u00eda nuclear a nivel mundial. As\u00ed, en 2013 ENUSA firm\u00f3 su primer contrato de suministro de equipos con el fabricante local CNNC Jianzhong Nuclear Fuel, principal fabricante de combustible chino. A \u00e9ste contrato siguieron otros dos firmados en el a\u00f1o 2014 para sendos suministros a la citada f\u00e1brica de combustible y al Suzhou Nuclear Power Research Institute (SNPI.) Es precisamente con \u00e9ste \u00faltimo y conjuntamente con su socio TECNATOM con quienes ENUSA ha firmado un nuevo acuerdo en enero de 2016 que puede suponer un salto cualitativo en las expectativas de la empresa espa\u00f1ola en el pa\u00eds asi\u00e1tico. SNPI pertenece al grupo China General Nuclear (CGN) que es el principal constructor y operador de reactores nucleares en China con 14 grupos en operaci\u00f3n y 12 m\u00e1s en construcci\u00f3n.\u00a0 El acuerdo con SNPI permite a ENUSA-TECNATOM ser los suministradores de referencia de equipos de inspecci\u00f3n de combustible nuclear para SNPI, lo que posiciona a los dos socios espa\u00f1oles en un lugar privilegiado ante el movimiento estrat\u00e9gico del grupo CGN: el desarrollo de sus propias capacidades de dise\u00f1o y fabricaci\u00f3n de combustible nuclear, actualmente en manos de su gran competidor, la CNNC.<\/p>\n<p>China es el pa\u00eds con m\u00e1s centrales nucleares en construcci\u00f3n (24 reactores) y con mayor potencial de mercado. En la actualidad, cuenta con 31 reactores nucleares en operaci\u00f3n, que producen el 2,4% de su electricidad. De los 66 reactores que hay en construcci\u00f3n en todo el mundo, 43 de ellos se construyen en el continente asi\u00e1tico.<\/p>\n<p><a href=\"http:\/\/www.enusa.es\/wp-content\/uploads\/2016\/04\/ENUSA-NIC-2016-2.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"Pabell\u00f3n de empresas nucleares espa\u00f1olas en la Feria Nuclear China del 6 al 9 de abril en Pek\u00edn. \" src=\"http:\/\/www.enusa.es\/wp-content\/uploads\/2016\/04\/ENUSA-NIC-2016-2-300x225.jpg\" alt=\"ENUSA NIC 2016\" width=\"300\" height=\"225\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>ENUSA ha viajado a Pek\u00edn, junto a otras empresas nucleares espa\u00f1olas y coordinadas por el Foro de la Industria Nuclear Espa\u00f1ola, para participar en la Nuclear Industry China (NIC 2016) que se celebra del 6 al 9 de abril. La participaci\u00f3n en la Feria NIC es una oportunidad para dar a conocer las novedades de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-2465","post","type-post","status-publish","format-standard","hentry","category-notas-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ENUSA presente desde hoy en la Feria Nuclear china - ENUSA | A company for the future<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.enusa.es\/en\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENUSA presente desde hoy en la Feria Nuclear china - ENUSA | A company for the future\" \/>\n<meta property=\"og:description\" content=\"ENUSA ha viajado a Pek\u00edn, junto a otras empresas nucleares espa\u00f1olas y coordinadas por el Foro de la Industria Nuclear Espa\u00f1ola, para participar en la Nuclear Industry China (NIC 2016) que se celebra del 6 al 9 de abril. La participaci\u00f3n en la Feria NIC es una oportunidad para dar a conocer las novedades de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.enusa.es\/en\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/\" \/>\n<meta property=\"og:site_name\" content=\"ENUSA | A company for the future\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-06T08:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T15:01:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.enusa.es\/wp-content\/uploads\/2016\/04\/ENUSA-NIC-2016-2-300x225.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/73d26d37c3085056c46d2e7d987fe9ce\"},\"headline\":\"ENUSA presente desde hoy en la Feria Nuclear china\",\"datePublished\":\"2016-04-06T08:00:14+00:00\",\"dateModified\":\"2024-02-07T15:01:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/\"},\"wordCount\":489,\"image\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/ENUSA-NIC-2016-2-300x225.jpg\",\"articleSection\":[\"Notas de prensa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/\",\"name\":\"ENUSA presente desde hoy en la Feria Nuclear china - ENUSA | A company for the future\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/ENUSA-NIC-2016-2-300x225.jpg\",\"datePublished\":\"2016-04-06T08:00:14+00:00\",\"dateModified\":\"2024-02-07T15:01:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/73d26d37c3085056c46d2e7d987fe9ce\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/ENUSA-NIC-2016-2-300x225.jpg\",\"contentUrl\":\"http:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/ENUSA-NIC-2016-2-300x225.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.enusa.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENUSA presente desde hoy en la Feria Nuclear china\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/\",\"name\":\"ENUSA | A company for the future\",\"description\":\"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.enusa.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/73d26d37c3085056c46d2e7d987fe9ce\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.enusa.es\"],\"url\":\"https:\\\/\\\/www.enusa.es\\\/en\\\/author\\\/divi-d55labs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENUSA presente desde hoy en la Feria Nuclear china - ENUSA | A company for the future","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.enusa.es\/en\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/","og_locale":"en_GB","og_type":"article","og_title":"ENUSA presente desde hoy en la Feria Nuclear china - ENUSA | A company for the future","og_description":"ENUSA ha viajado a Pek\u00edn, junto a otras empresas nucleares espa\u00f1olas y coordinadas por el Foro de la Industria Nuclear Espa\u00f1ola, para participar en la Nuclear Industry China (NIC 2016) que se celebra del 6 al 9 de abril. La participaci\u00f3n en la Feria NIC es una oportunidad para dar a conocer las novedades de [&hellip;]","og_url":"https:\/\/www.enusa.es\/en\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/","og_site_name":"ENUSA | A company for the future","article_published_time":"2016-04-06T08:00:14+00:00","article_modified_time":"2024-02-07T15:01:42+00:00","og_image":[{"url":"http:\/\/www.enusa.es\/wp-content\/uploads\/2016\/04\/ENUSA-NIC-2016-2-300x225.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/#article","isPartOf":{"@id":"https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/"},"author":{"name":"admin","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/73d26d37c3085056c46d2e7d987fe9ce"},"headline":"ENUSA presente desde hoy en la Feria Nuclear china","datePublished":"2016-04-06T08:00:14+00:00","dateModified":"2024-02-07T15:01:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/"},"wordCount":489,"image":{"@id":"https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/#primaryimage"},"thumbnailUrl":"http:\/\/www.enusa.es\/wp-content\/uploads\/2016\/04\/ENUSA-NIC-2016-2-300x225.jpg","articleSection":["Notas de prensa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/","url":"https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/","name":"ENUSA presente desde hoy en la Feria Nuclear china - ENUSA | A company for the future","isPartOf":{"@id":"https:\/\/www.enusa.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/#primaryimage"},"image":{"@id":"https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/#primaryimage"},"thumbnailUrl":"http:\/\/www.enusa.es\/wp-content\/uploads\/2016\/04\/ENUSA-NIC-2016-2-300x225.jpg","datePublished":"2016-04-06T08:00:14+00:00","dateModified":"2024-02-07T15:01:42+00:00","author":{"@id":"https:\/\/www.enusa.es\/#\/schema\/person\/73d26d37c3085056c46d2e7d987fe9ce"},"breadcrumb":{"@id":"https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/#primaryimage","url":"http:\/\/www.enusa.es\/wp-content\/uploads\/2016\/04\/ENUSA-NIC-2016-2-300x225.jpg","contentUrl":"http:\/\/www.enusa.es\/wp-content\/uploads\/2016\/04\/ENUSA-NIC-2016-2-300x225.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.enusa.es\/enusa-presente-desde-hoy-en-la-feria-nuclear-china\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.enusa.es\/"},{"@type":"ListItem","position":2,"name":"ENUSA presente desde hoy en la Feria Nuclear china"}]},{"@type":"WebSite","@id":"https:\/\/www.enusa.es\/#website","url":"https:\/\/www.enusa.es\/","name":"ENUSA | A company for the future","description":"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.enusa.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/73d26d37c3085056c46d2e7d987fe9ce","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab34fdb663e8f5aaac216ce3bba8eea7364d56eb0be3fb7cee79ae0cbe1bd50d?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.enusa.es"],"url":"https:\/\/www.enusa.es\/en\/author\/divi-d55labs\/"}]}},"_links":{"self":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/2465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/comments?post=2465"}],"version-history":[{"count":1,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/2465\/revisions"}],"predecessor-version":[{"id":19985,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/2465\/revisions\/19985"}],"wp:attachment":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/media?parent=2465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/categories?post=2465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/tags?post=2465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}