{"id":3331,"date":"2017-10-27T10:20:34","date_gmt":"2017-10-27T10:20:34","guid":{"rendered":"http:\/\/www.enusa.es\/?p=3331"},"modified":"2024-02-07T13:22:38","modified_gmt":"2024-02-07T12:22:38","slug":"enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel","status":"publish","type":"post","link":"https:\/\/www.enusa.es\/en\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/","title":{"rendered":"ENUSA\/Westinghouse celebran un seminario t\u00e9cnico con Engie-Electrabel\/Tractebel"},"content":{"rendered":"<p>Viernes, 27 de octubre de 2017. El martes 24 y mi\u00e9rcoles 25 de octubre ha tenido lugar un Seminario T\u00e9cnico con Engie Electrabel y Tractebel en la localidad belga de Genval. En el evento se ha contado con una nutrida representaci\u00f3n, tanto por parte del cliente proveniente de las oficinas centrales y de las propias plantas de Doel y Tihange, como por parte de Westinghouse y ENUSA.<\/p>\n<p>La apertura del Seminario corri\u00f3 a cargo de Jose Luis Gonz\u00e1lez, quien hizo un repaso de los principales retos que se est\u00e1n abordando en la actualidad as\u00ed como de la experiencia vivida desde 1992, a\u00f1o en el que se firma el primer contrato de suministro de combustible para Doel 4.<\/p>\n<p>Rony Verdickt, Responsable Corporativo de Combustible Nuclear de Engie Electrabel, comparti\u00f3 por su parte con los asistentes la importancia que para ellos tiene el suministro de un combustible seguro y fiable y los retos asociados a la introducci\u00f3n de nuevos productos en B\u00e9lgica, no sin olvidar que, para alcanzar el \u00e9xito en cualquiera de los proyectos conjuntos, es necesario el mutuo conocimiento personal y la continua interacci\u00f3n entre las organizaciones del cliente y de Westinghouse-ENUSA.<\/p>\n<p>Durante el primer d\u00eda se abordaron temas de gran inter\u00e9s, como el proyecto de licenciamiento e introducci\u00f3n de combustible RFA-2 Opt en Doel 3 y Tihange 2 y los retos asociados, el soporte de ENUSA y Westinghouse a la operaci\u00f3n a largo plazo en B\u00e9lgica mediante el dise\u00f1o y carga de Shielding Fuel Assemblies y la visi\u00f3n a medio y largo plazo de los productos y servicios de ingenier\u00eda con especial \u00e9nfasis en el \u00abAccident Tolerant Fuel\u00bb.<\/p>\n<p><a href=\"http:\/\/www.enusa.es\/wp-content\/uploads\/2017\/10\/SeminarioT\u00e9cnicoB\u00e9lgica.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-3330\" src=\"http:\/\/www.enusa.es\/wp-content\/uploads\/2017\/10\/SeminarioT\u00e9cnicoB\u00e9lgica-300x210.png\" alt=\"\" width=\"492\" height=\"345\" \/><\/a><\/p>\n<p>Durante el segundo d\u00eda del seminario, se present\u00f3 una actualizaci\u00f3n detallada de los procesos de fabricaci\u00f3n e inspecci\u00f3n en Juzbado y de las acciones adoptadas a nivel de ENUSA-Westinghouse para garantizar el suministro de combustible a los cuatro reactores Doel 4, Doel 3 y Tihange 3 y Tihange 2. Se ha hecho, as\u00ed mismo, una revisi\u00f3n de la necesidad de flexibilidad en la operaci\u00f3n y de c\u00f3mo el EFG est\u00e1 prestando apoyo al cliente en este \u00e1rea.<\/p>\n<p>En sesi\u00f3n paralela, se trataron otros temas de relevancia para el cliente como son la gesti\u00f3n de combustible gastado en B\u00e9lgica y las actividades que a ese respecto realiza ENUSA, se hizo una actualizaci\u00f3n al cliente de las capacidades para la prestaci\u00f3n de servicios en central, terminando con una presentaci\u00f3n sobre seguimiento de qu\u00edmica del primario.<\/p>\n<p>Para finalizar, se\u00f1alar que el buen ambiente en el que se ha desarrollado el seminario ratifica la gran confianza que Engie Electrabel Tractebel tiene depositada en ENUSA\/Westinghouse avalada, por otra parte, por los compromisos actuales de suministro de combustible a cuatro de los siete reactores nucleares que componen el parque belga.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Viernes, 27 de octubre de 2017. El martes 24 y mi\u00e9rcoles 25 de octubre ha tenido lugar un Seminario T\u00e9cnico con Engie Electrabel y Tractebel en la localidad belga de Genval. En el evento se ha contado con una nutrida representaci\u00f3n, tanto por parte del cliente proveniente de las oficinas centrales y de las propias [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-3331","post","type-post","status-publish","format-standard","hentry","category-notas-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ENUSA\/Westinghouse celebran un seminario t\u00e9cnico con Engie-Electrabel\/Tractebel - ENUSA | A company for the future<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.enusa.es\/en\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENUSA\/Westinghouse celebran un seminario t\u00e9cnico con Engie-Electrabel\/Tractebel - ENUSA | A company for the future\" \/>\n<meta property=\"og:description\" content=\"Viernes, 27 de octubre de 2017. El martes 24 y mi\u00e9rcoles 25 de octubre ha tenido lugar un Seminario T\u00e9cnico con Engie Electrabel y Tractebel en la localidad belga de Genval. En el evento se ha contado con una nutrida representaci\u00f3n, tanto por parte del cliente proveniente de las oficinas centrales y de las propias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.enusa.es\/en\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/\" \/>\n<meta property=\"og:site_name\" content=\"ENUSA | A company for the future\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-27T10:20:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T12:22:38+00:00\" \/>\n<meta name=\"author\" content=\"Ignacio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ignacio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\\\/\"},\"author\":{\"name\":\"Ignacio\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"headline\":\"ENUSA\\\/Westinghouse celebran un seminario t\u00e9cnico con Engie-Electrabel\\\/Tractebel\",\"datePublished\":\"2017-10-27T10:20:34+00:00\",\"dateModified\":\"2024-02-07T12:22:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\\\/\"},\"wordCount\":486,\"articleSection\":[\"Notas de prensa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\\\/\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\\\/\",\"name\":\"ENUSA\\\/Westinghouse celebran un seminario t\u00e9cnico con Engie-Electrabel\\\/Tractebel - ENUSA | A company for the future\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\"},\"datePublished\":\"2017-10-27T10:20:34+00:00\",\"dateModified\":\"2024-02-07T12:22:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.enusa.es\\\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.enusa.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENUSA\\\/Westinghouse celebran un seminario t\u00e9cnico con Engie-Electrabel\\\/Tractebel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/\",\"name\":\"ENUSA | A company for the future\",\"description\":\"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.enusa.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\",\"name\":\"Ignacio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"caption\":\"Ignacio\"},\"url\":\"https:\\\/\\\/www.enusa.es\\\/en\\\/author\\\/admin-enusa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENUSA\/Westinghouse celebran un seminario t\u00e9cnico con Engie-Electrabel\/Tractebel - ENUSA | A company for the future","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.enusa.es\/en\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/","og_locale":"en_GB","og_type":"article","og_title":"ENUSA\/Westinghouse celebran un seminario t\u00e9cnico con Engie-Electrabel\/Tractebel - ENUSA | A company for the future","og_description":"Viernes, 27 de octubre de 2017. El martes 24 y mi\u00e9rcoles 25 de octubre ha tenido lugar un Seminario T\u00e9cnico con Engie Electrabel y Tractebel en la localidad belga de Genval. En el evento se ha contado con una nutrida representaci\u00f3n, tanto por parte del cliente proveniente de las oficinas centrales y de las propias [&hellip;]","og_url":"https:\/\/www.enusa.es\/en\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/","og_site_name":"ENUSA | A company for the future","article_published_time":"2017-10-27T10:20:34+00:00","article_modified_time":"2024-02-07T12:22:38+00:00","author":"Ignacio","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ignacio","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.enusa.es\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/#article","isPartOf":{"@id":"https:\/\/www.enusa.es\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/"},"author":{"name":"Ignacio","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"headline":"ENUSA\/Westinghouse celebran un seminario t\u00e9cnico con Engie-Electrabel\/Tractebel","datePublished":"2017-10-27T10:20:34+00:00","dateModified":"2024-02-07T12:22:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.enusa.es\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/"},"wordCount":486,"articleSection":["Notas de prensa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.enusa.es\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/","url":"https:\/\/www.enusa.es\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/","name":"ENUSA\/Westinghouse celebran un seminario t\u00e9cnico con Engie-Electrabel\/Tractebel - ENUSA | A company for the future","isPartOf":{"@id":"https:\/\/www.enusa.es\/#website"},"datePublished":"2017-10-27T10:20:34+00:00","dateModified":"2024-02-07T12:22:38+00:00","author":{"@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"breadcrumb":{"@id":"https:\/\/www.enusa.es\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.enusa.es\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.enusa.es\/enusawestinghouse-celebran-un-seminario-tecnico-con-engie-electrabeltractebel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.enusa.es\/"},{"@type":"ListItem","position":2,"name":"ENUSA\/Westinghouse celebran un seminario t\u00e9cnico con Engie-Electrabel\/Tractebel"}]},{"@type":"WebSite","@id":"https:\/\/www.enusa.es\/#website","url":"https:\/\/www.enusa.es\/","name":"ENUSA | A company for the future","description":"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.enusa.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834","name":"Ignacio","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","caption":"Ignacio"},"url":"https:\/\/www.enusa.es\/en\/author\/admin-enusa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/3331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/comments?post=3331"}],"version-history":[{"count":1,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/3331\/revisions"}],"predecessor-version":[{"id":19899,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/3331\/revisions\/19899"}],"wp:attachment":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/media?parent=3331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/categories?post=3331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/tags?post=3331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}