{"id":3423,"date":"2018-04-25T08:53:21","date_gmt":"2018-04-25T08:53:21","guid":{"rendered":"http:\/\/www.enusa.es\/?p=3423"},"modified":"2024-02-07T12:56:25","modified_gmt":"2024-02-07T11:56:25","slug":"enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero","status":"publish","type":"post","link":"https:\/\/www.enusa.es\/en\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/","title":{"rendered":"ENUSA rubrica el Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en materia de violencia de g\u00e9nero"},"content":{"rendered":"<p>25\/04\/2018. El pasado 12 de febrero de 2018, la Ministra de Sanidad, Servicios Sociales e Igualdad y la Presidenta de SEPI firmaron un Acuerdo de colaboraci\u00f3n para promover la sensibilizaci\u00f3n sobre la violencia de g\u00e9nero.<\/p>\n<p>ENUSA ha suscrito este Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en el que ratifica que conoce el Convenio para promover la sensibilizaci\u00f3n sobre la violencia de g\u00e9nero suscrito por la Sociedad Estatal de Participaciones Industriales, SEPI, con el Ministerio de Sanidad, Servicios Sociales e Igualdad. La compa\u00f1\u00eda formaliza de esta forma su adhesi\u00f3n al indicado Convenio y acepta y asume los compromisos de colaborar en la difusi\u00f3n de campa\u00f1as de sensibilizaci\u00f3n y prevenci\u00f3n de la violencia de g\u00e9nero.<\/p>\n<p>ENUSA se suma as\u00ed a la iniciativa \u201cEmpresas por una sociedad libre de violencia de g\u00e9nero\u201d, incorpor\u00e1ndose al resto de empresas p\u00fablicas que ya est\u00e1n adheridas a la iniciativa desde el pasado 2013, para promover actuaciones de sensibilizaci\u00f3n sobre la violencia de g\u00e9nero, y hacer que el mensaje #haysalida tenga un gran alcance e impacto. <\/p>\n<p>La iniciativa \u201cEmpresas por una sociedad libre de violencia de g\u00e9nero\u201d, nace en el a\u00f1o 2012 con el fin de aprovechar el potencial de la empresa como agente social de desarrollo para que el mensaje de sensibilizaci\u00f3n y concienciaci\u00f3n contra la violencia de g\u00e9nero llegue a todos los rincones de la sociedad. Mediante esta firma de adhesi\u00f3n ENUSA se suma, asimismo, al Pacto de Estado contra la Violencia de G\u00e9nero.<\/p>\n<p>Entre los objetivos prioritarios del Ministerio de Sanidad, Servicios Sociales e Igualdad se encuentra la adopci\u00f3n de medidas espec\u00edficas dirigidas a las mujeres v\u00edctimas de violencia de genero a trav\u00e9s del impulso y desarrollo de medidas de sensibilizaci\u00f3n ciudadana con el fin de prevenir la violencia de g\u00e9nero, y de la promoci\u00f3n de la colaboraci\u00f3n y participaci\u00f3n de las organizaciones de la sociedad civil que act\u00faan contra esa forma de violencia.<\/p>\n<p>SEPI es consciente de la problem\u00e1tica social existente, de la necesaria implicaci\u00f3n de los agentes sociales en la prevenci\u00f3n y de la importancia de contribuir a la sensibilizaci\u00f3n contra la violencia de g\u00e9nero. Y por estas razones, se compromete a colaborar en la difusi\u00f3n de campa\u00f1as de sensibilizaci\u00f3n y prevenci\u00f3n de la violencia de g\u00e9nero, tanto a nivel interno de la entidad como externo. Una de las formas de difusi\u00f3n es procurar la adhesi\u00f3n de cada una de las sociedades filiales.<\/p>\n<p>Se crea una Comisi\u00f3n Mixta de Seguimiento constituida por dos representantes de cada una de las partes, que se reunir\u00e1 como m\u00ednimo una vez al a\u00f1o, sin perjuicio de que pueda ser convocada con car\u00e1cter extraordinario a petici\u00f3n de cada una de las partes.<\/p>","protected":false},"excerpt":{"rendered":"<p>25\/04\/2018. El pasado 12 de febrero de 2018, la Ministra de Sanidad, Servicios Sociales e Igualdad y la Presidenta de SEPI firmaron un Acuerdo de colaboraci\u00f3n para promover la sensibilizaci\u00f3n sobre la violencia de g\u00e9nero. ENUSA ha suscrito este Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en el que ratifica que conoce el Convenio para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-3423","post","type-post","status-publish","format-standard","hentry","category-notas-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ENUSA rubrica el Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en materia de violencia de g\u00e9nero - ENUSA | A company for the future<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.enusa.es\/en\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENUSA rubrica el Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en materia de violencia de g\u00e9nero - ENUSA | A company for the future\" \/>\n<meta property=\"og:description\" content=\"25\/04\/2018. El pasado 12 de febrero de 2018, la Ministra de Sanidad, Servicios Sociales e Igualdad y la Presidenta de SEPI firmaron un Acuerdo de colaboraci\u00f3n para promover la sensibilizaci\u00f3n sobre la violencia de g\u00e9nero. ENUSA ha suscrito este Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en el que ratifica que conoce el Convenio para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.enusa.es\/en\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/\" \/>\n<meta property=\"og:site_name\" content=\"ENUSA | A company for the future\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-25T08:53:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T11:56:25+00:00\" \/>\n<meta name=\"author\" content=\"Ignacio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ignacio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\\\/\"},\"author\":{\"name\":\"Ignacio\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"headline\":\"ENUSA rubrica el Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en materia de violencia de g\u00e9nero\",\"datePublished\":\"2018-04-25T08:53:21+00:00\",\"dateModified\":\"2024-02-07T11:56:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\\\/\"},\"wordCount\":503,\"articleSection\":[\"Notas de prensa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\\\/\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\\\/\",\"name\":\"ENUSA rubrica el Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en materia de violencia de g\u00e9nero - ENUSA | A company for the future\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\"},\"datePublished\":\"2018-04-25T08:53:21+00:00\",\"dateModified\":\"2024-02-07T11:56:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.enusa.es\\\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.enusa.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENUSA rubrica el Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en materia de violencia de g\u00e9nero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/\",\"name\":\"ENUSA | A company for the future\",\"description\":\"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.enusa.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\",\"name\":\"Ignacio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"caption\":\"Ignacio\"},\"url\":\"https:\\\/\\\/www.enusa.es\\\/en\\\/author\\\/admin-enusa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENUSA rubrica el Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en materia de violencia de g\u00e9nero - ENUSA | A company for the future","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.enusa.es\/en\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/","og_locale":"en_GB","og_type":"article","og_title":"ENUSA rubrica el Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en materia de violencia de g\u00e9nero - ENUSA | A company for the future","og_description":"25\/04\/2018. El pasado 12 de febrero de 2018, la Ministra de Sanidad, Servicios Sociales e Igualdad y la Presidenta de SEPI firmaron un Acuerdo de colaboraci\u00f3n para promover la sensibilizaci\u00f3n sobre la violencia de g\u00e9nero. ENUSA ha suscrito este Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en el que ratifica que conoce el Convenio para [&hellip;]","og_url":"https:\/\/www.enusa.es\/en\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/","og_site_name":"ENUSA | A company for the future","article_published_time":"2018-04-25T08:53:21+00:00","article_modified_time":"2024-02-07T11:56:25+00:00","author":"Ignacio","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ignacio","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.enusa.es\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/#article","isPartOf":{"@id":"https:\/\/www.enusa.es\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/"},"author":{"name":"Ignacio","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"headline":"ENUSA rubrica el Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en materia de violencia de g\u00e9nero","datePublished":"2018-04-25T08:53:21+00:00","dateModified":"2024-02-07T11:56:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.enusa.es\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/"},"wordCount":503,"articleSection":["Notas de prensa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.enusa.es\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/","url":"https:\/\/www.enusa.es\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/","name":"ENUSA rubrica el Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en materia de violencia de g\u00e9nero - ENUSA | A company for the future","isPartOf":{"@id":"https:\/\/www.enusa.es\/#website"},"datePublished":"2018-04-25T08:53:21+00:00","dateModified":"2024-02-07T11:56:25+00:00","author":{"@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"breadcrumb":{"@id":"https:\/\/www.enusa.es\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.enusa.es\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.enusa.es\/enusa-rubrica-el-acuerdo-de-adhesion-al-convenio-de-colaboracion-en-materia-de-violencia-de-genero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.enusa.es\/"},{"@type":"ListItem","position":2,"name":"ENUSA rubrica el Acuerdo de Adhesi\u00f3n al Convenio de Colaboraci\u00f3n en materia de violencia de g\u00e9nero"}]},{"@type":"WebSite","@id":"https:\/\/www.enusa.es\/#website","url":"https:\/\/www.enusa.es\/","name":"ENUSA | A company for the future","description":"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.enusa.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834","name":"Ignacio","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","caption":"Ignacio"},"url":"https:\/\/www.enusa.es\/en\/author\/admin-enusa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/3423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/comments?post=3423"}],"version-history":[{"count":1,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/3423\/revisions"}],"predecessor-version":[{"id":19850,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/3423\/revisions\/19850"}],"wp:attachment":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/media?parent=3423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/categories?post=3423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/tags?post=3423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}