{"id":3934,"date":"2018-12-05T09:34:29","date_gmt":"2018-12-05T09:34:29","guid":{"rendered":"http:\/\/www.enusa.es\/?p=3934"},"modified":"2024-02-14T13:20:00","modified_gmt":"2024-02-14T12:20:00","slug":"el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa","status":"publish","type":"post","link":"https:\/\/www.enusa.es\/en\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/","title":{"rendered":"El Grupo de Voluntariado de ENUSA hace entrega a Asi\u00f3n del cheque y de los alimentos donados por los empleados y la empresa"},"content":{"rendered":"<blockquote>\n<h5><strong>La iniciativa \u00abENUSA Uno+1\u00bb ha batido el r\u00e9cord en lo que a recogida de alimentos se refiere. A la contribuci\u00f3n hecha por los empleados y empleadas, ENUSA ha sumado un euro por cada uno de los kilos de alimentos aportados<\/strong><\/h5>\n<h5><strong>Asi\u00f3n es una asociaci\u00f3n de Padres de Ni\u00f1os con c\u00e1ncer que, adem\u00e1s de proporcionar acogida a los padres de ni\u00f1os hospitalizados, evita las hospitalizaciones a ni\u00f1os que pueden seguir un tratamiento desde casa, pero cerca del centro hospitalario<\/strong><\/h5>\n<\/blockquote>\n<p>El Grupo de Voluntariado de ENUSA ha hecho entrega a la Asociaci\u00f3n Infantil Oncol\u00f3gica de Madrid el cheque y los alimentos recaudados con la iniciativa \u00abENUSA uno+1\u00bb. Como en ediciones anteriores, la empresa contribu\u00eda con un euro por cada kilo de alimentos recogidos y, en esta edici\u00f3n se han batido los r\u00e9cords de a\u00f1os anteriores.<\/p>\n<p>Asi\u00f3n es una asociaci\u00f3n de Padres de Ni\u00f1os con c\u00e1ncer que presta apoyo integral a las familias que se tienen que trasladar desde sus domicilios a Madrid para que sus hijos e hijas reciban tratamientos oncol\u00f3gicos.<\/p>\n<p>Se trata de una organizaci\u00f3n reconocida como entidad p\u00fablica desde 1995 que contribuye al mejor estado de ni\u00f1os y adolescentes diagnosticados de c\u00e1ncer y de sus padres, tanto en el plano m\u00e9dico, como psicol\u00f3gico y asistencial trabajando para que el desarrollo afectivo y educativo de los ni\u00f1os y sus familias sea el m\u00e1s adecuado a sus especiales circunstancias.<\/p>\n<p>Adem\u00e1s del apoyo psicol\u00f3gico, Asi\u00f3n proporciona a las familias apoyo econ\u00f3mico proporcionando alojamientos familiares en los que, adem\u00e1s de los progenitores, puedan residir los ni\u00f1os y ni\u00f1as que reciben tratamiento externo, pero que precisan estar cerca del centro hospitalario donde reciben tratamiento.<\/p>\n<p>Durante 2017, 77 familias han podido ser acogidas en los hogares que dispone Asi\u00f3n y han evitado 801 hospitalizaciones de 66 ni\u00f1os. Adem\u00e1s, 958 ni\u00f1os participaron en las actividades de ocio que se llevan a cabo en los hospitales por parte de los 488 voluntarios que trabajan con esta organizaci\u00f3n.<\/p>\n<p>En la entrega del cheque ha estado presente el presidente de ENUSA, Jos\u00e9 Vicente Berlanga, que ha mostrado su agradecimiento al equipo promotor de la iniciativa para una causa \u00absiempre necesaria, pero m\u00e1s cuando se trata de ni\u00f1os\u00bb y ha manifestado a las representantes de Asi\u00f3n, su voluntad de seguir participando con la asociaci\u00f3n en distintas actividades, por ejemplo, en la labor de concienciaci\u00f3n cara a al 15 de febrero, D\u00eda Internacional del C\u00e1ncer Infantil. Para Jos\u00e9 Vicente Berlanga, \u00abnuestro Grupo de Voluntariado es la mejor cara de ENUSA ante la sociedad\u00bb<\/p>\n<p>Charo Ar\u00e9valo, responsable de la direcci\u00f3n de Responsabilidad Social Corporativa, del que emana este equipo, ha querido agradecer \u00abel magn\u00edfico trabajo hecho por el Grupo de Voluntariado, su implicaci\u00f3n e ilusi\u00f3n\u00bb que revierte en poder ayudar \u00aba quien tanto ayuda\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>La iniciativa \u00abENUSA Uno+1\u00bb ha batido el r\u00e9cord en lo que a recogida de alimentos se refiere. A la contribuci\u00f3n hecha por los empleados y empleadas, ENUSA ha sumado un euro por cada uno de los kilos de alimentos aportados Asi\u00f3n es una asociaci\u00f3n de Padres de Ni\u00f1os con c\u00e1ncer que, adem\u00e1s de proporcionar acogida [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-3934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Grupo de Voluntariado de ENUSA hace entrega a Asi\u00f3n del cheque y de los alimentos donados por los empleados y la empresa - ENUSA | A company for the future<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.enusa.es\/en\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Grupo de Voluntariado de ENUSA hace entrega a Asi\u00f3n del cheque y de los alimentos donados por los empleados y la empresa - ENUSA | A company for the future\" \/>\n<meta property=\"og:description\" content=\"La iniciativa \u00abENUSA Uno+1\u00bb ha batido el r\u00e9cord en lo que a recogida de alimentos se refiere. A la contribuci\u00f3n hecha por los empleados y empleadas, ENUSA ha sumado un euro por cada uno de los kilos de alimentos aportados Asi\u00f3n es una asociaci\u00f3n de Padres de Ni\u00f1os con c\u00e1ncer que, adem\u00e1s de proporcionar acogida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.enusa.es\/en\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/\" \/>\n<meta property=\"og:site_name\" content=\"ENUSA | A company for the future\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-05T09:34:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T12:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.enusa.es\/wp-content\/uploads\/2024\/02\/posts_image_placeholder3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ignacio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ignacio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/\"},\"author\":{\"name\":\"Ignacio\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"headline\":\"El Grupo de Voluntariado de ENUSA hace entrega a Asi\u00f3n del cheque y de los alimentos donados por los empleados y la empresa\",\"datePublished\":\"2018-12-05T09:34:29+00:00\",\"dateModified\":\"2024-02-14T12:20:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/\"},\"wordCount\":519,\"image\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/posts_image_placeholder3.jpg\",\"articleSection\":[\"Notas de prensa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/\",\"name\":\"El Grupo de Voluntariado de ENUSA hace entrega a Asi\u00f3n del cheque y de los alimentos donados por los empleados y la empresa - ENUSA | A company for the future\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/posts_image_placeholder3.jpg\",\"datePublished\":\"2018-12-05T09:34:29+00:00\",\"dateModified\":\"2024-02-14T12:20:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/posts_image_placeholder3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.enusa.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/posts_image_placeholder3.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.enusa.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Grupo de Voluntariado de ENUSA hace entrega a Asi\u00f3n del cheque y de los alimentos donados por los empleados y la empresa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#website\",\"url\":\"https:\\\/\\\/www.enusa.es\\\/\",\"name\":\"ENUSA | A company for the future\",\"description\":\"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.enusa.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.enusa.es\\\/#\\\/schema\\\/person\\\/050a681149718523703fca27c059c834\",\"name\":\"Ignacio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g\",\"caption\":\"Ignacio\"},\"url\":\"https:\\\/\\\/www.enusa.es\\\/en\\\/author\\\/admin-enusa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Grupo de Voluntariado de ENUSA hace entrega a Asi\u00f3n del cheque y de los alimentos donados por los empleados y la empresa - ENUSA | A company for the future","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.enusa.es\/en\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/","og_locale":"en_GB","og_type":"article","og_title":"El Grupo de Voluntariado de ENUSA hace entrega a Asi\u00f3n del cheque y de los alimentos donados por los empleados y la empresa - ENUSA | A company for the future","og_description":"La iniciativa \u00abENUSA Uno+1\u00bb ha batido el r\u00e9cord en lo que a recogida de alimentos se refiere. A la contribuci\u00f3n hecha por los empleados y empleadas, ENUSA ha sumado un euro por cada uno de los kilos de alimentos aportados Asi\u00f3n es una asociaci\u00f3n de Padres de Ni\u00f1os con c\u00e1ncer que, adem\u00e1s de proporcionar acogida [&hellip;]","og_url":"https:\/\/www.enusa.es\/en\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/","og_site_name":"ENUSA | A company for the future","article_published_time":"2018-12-05T09:34:29+00:00","article_modified_time":"2024-02-14T12:20:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.enusa.es\/wp-content\/uploads\/2024\/02\/posts_image_placeholder3.jpg","type":"image\/jpeg"}],"author":"Ignacio","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ignacio","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/#article","isPartOf":{"@id":"https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/"},"author":{"name":"Ignacio","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"headline":"El Grupo de Voluntariado de ENUSA hace entrega a Asi\u00f3n del cheque y de los alimentos donados por los empleados y la empresa","datePublished":"2018-12-05T09:34:29+00:00","dateModified":"2024-02-14T12:20:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/"},"wordCount":519,"image":{"@id":"https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.enusa.es\/wp-content\/uploads\/2024\/02\/posts_image_placeholder3.jpg","articleSection":["Notas de prensa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/","url":"https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/","name":"El Grupo de Voluntariado de ENUSA hace entrega a Asi\u00f3n del cheque y de los alimentos donados por los empleados y la empresa - ENUSA | A company for the future","isPartOf":{"@id":"https:\/\/www.enusa.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/#primaryimage"},"image":{"@id":"https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.enusa.es\/wp-content\/uploads\/2024\/02\/posts_image_placeholder3.jpg","datePublished":"2018-12-05T09:34:29+00:00","dateModified":"2024-02-14T12:20:00+00:00","author":{"@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834"},"breadcrumb":{"@id":"https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/#primaryimage","url":"https:\/\/www.enusa.es\/wp-content\/uploads\/2024\/02\/posts_image_placeholder3.jpg","contentUrl":"https:\/\/www.enusa.es\/wp-content\/uploads\/2024\/02\/posts_image_placeholder3.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.enusa.es\/el-grupo-de-voluntariado-de-enusa-hace-entrega-a-asion-del-cheque-y-de-los-alimentos-donados-por-los-empleados-y-la-empresa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.enusa.es\/"},{"@type":"ListItem","position":2,"name":"El Grupo de Voluntariado de ENUSA hace entrega a Asi\u00f3n del cheque y de los alimentos donados por los empleados y la empresa"}]},{"@type":"WebSite","@id":"https:\/\/www.enusa.es\/#website","url":"https:\/\/www.enusa.es\/","name":"ENUSA | A company for the future","description":"Nuestro prop\u00f3sito es desarrollar soluciones innovadoras nucleares y medioambientales, contribuyendo al progreso sostenible de la sociedad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.enusa.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.enusa.es\/#\/schema\/person\/050a681149718523703fca27c059c834","name":"Ignacio","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/884d1e5743df442e9d9ad60d7c6035c655516e0bce34177968dce067d09b5c31?s=96&d=mm&r=g","caption":"Ignacio"},"url":"https:\/\/www.enusa.es\/en\/author\/admin-enusa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/3934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/comments?post=3934"}],"version-history":[{"count":1,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/3934\/revisions"}],"predecessor-version":[{"id":19812,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/posts\/3934\/revisions\/19812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/media\/20862"}],"wp:attachment":[{"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/media?parent=3934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/categories?post=3934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enusa.es\/en\/wp-json\/wp\/v2\/tags?post=3934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}